{"id":58880,"date":"2024-01-19T15:10:17","date_gmt":"2024-01-19T07:10:17","guid":{"rendered":"https:\/\/bsghgranulator.com\/?page_id=58880"},"modified":"2026-03-11T10:07:24","modified_gmt":"2026-03-11T02:07:24","slug":"small-metal-shredder","status":"publish","type":"page","link":"https:\/\/bsghgranulator.com\/de\/kleiner-metallschredder\/","title":{"rendered":"Kleiner Metallschredder"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"58880\" class=\"elementor elementor-58880\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70943647 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"70943647\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/youtu.be\\\/-Am9Ja3KGRQ&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-354ea0dc\" data-id=\"354ea0dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1adf84f4 elementor-widget elementor-widget-heading\" data-id=\"1adf84f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">hocheffiziente kleine Metallzerkleinerermaschine<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-495ba4b5 elementor-widget elementor-widget-text-editor\" data-id=\"495ba4b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei Arbeiten im kleineren Ma\u00dfstab ist ein kleiner Metallschredder ein wichtiges Werkzeug zur Verarbeitung verschiedener Arten von Metallschrott und auch anderer Materialien wie Paletten, Kunststoff, F\u00e4sser usw. Aufgrund seiner geringen Gr\u00f6\u00dfe passt er problemlos in enge Bereiche und ist ein leistungsstarkes Mittel zum Zerkleinern von Metallabf\u00e4llen. Dieser Schredder eignet sich hervorragend f\u00fcr Werkst\u00e4tten, kleine Recyclinganlagen oder Unternehmen, die mit Metallabf\u00e4llen umgehen, da er verschiedene Metallarten schnell und einfach zerschneidet und gro\u00dfe St\u00fccke in kleinere, leichter zu handhabende St\u00fccke zerlegt. Seine robuste Konstruktion macht ihn langlebig und zuverl\u00e4ssig, und die Tatsache, dass er effizient arbeitet, tr\u00e4gt dazu bei, Metallabf\u00e4lle zu reduzieren. Diese Maschine eignet sich gut f\u00fcr Personen, die Metallschrott effizienter und kontrollierter handhaben m\u00fcssen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cadb462 elementor-widget elementor-widget-button\" data-id=\"5cadb462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjY3MDI0IiwidG9nZ2xlIjpmYWxzZX0=\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Holen Sie sich ein Angebot<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-449e04a1 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"449e04a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c372bc0\" data-id=\"3c372bc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33a6878d elementor-widget elementor-widget-heading\" data-id=\"33a6878d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Unsere Mini-Industrie-Metallzerkleinerer<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b17d48f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2b17d48f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir sorgen f\u00fcr hochwertige Kleinmetall-Schredderanlagen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ebe28b elementor-widget elementor-widget-text-editor\" data-id=\"53ebe28b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bieten eine breite Palette an Metallschreddermaschinen an, wobei unsere kleinen Metallschreddermaschinen der Inbegriff von Zuverl\u00e4ssigkeit und hoher Qualit\u00e4t sind. Mit dem Fokus auf Genauigkeit und Effizienz sind diese Schredder darauf ausgelegt, die vielf\u00e4ltigen Anforderungen der Metallverarbeitung zu erf\u00fcllen.<\/p><p>Jede Maschine wird aus einer Kombination hochwertiger Materialien und moderner Technologie hergestellt. Unsere Klingen bestehen beispielsweise aus dem besseren Material H13. (Wir k\u00f6nnen sie auch entsprechend Ihrer tats\u00e4chlichen Situation mit anderen Materialien anpassen.) Daher ist die Klinge von guter Qualit\u00e4t und hat eine lange Lebensdauer, Sie k\u00f6nnen sie vertrauensvoll verwenden. Wir stellen sicher, dass jeder Aktenvernichter gleichbleibend gut funktioniert, indem wir ihn gr\u00fcndlich testen und seine Qualit\u00e4t immer wieder \u00fcberpr\u00fcfen. Diese Aktenvernichter eignen sich hervorragend f\u00fcr viele verschiedene Schneidaufgaben, da sie sowohl leistungsstark als auch effizient sind. Sie sind eine gute Wahl f\u00fcr alle, die zuverl\u00e4ssige Aktenvernichter f\u00fcr die Metallverarbeitung ben\u00f6tigen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-537ef9fb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"537ef9fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38cc6a51 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38cc6a51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fb5e6c5\" data-id=\"1fb5e6c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b32451 elementor-widget elementor-widget-heading\" data-id=\"8b32451\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kleiner Metallschredder der MS-Serie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6157248 elementor-widget elementor-widget-text-editor\" data-id=\"6157248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Aktenvernichter der MS-Serie sind innovative kleine Maschinen mit zweiachsiger Welle und einzigartigem Design, die von einem oder zwei Motoren angetrieben werden. Mit ihrer synchronisierten zweiachsigen Bewegung, die von einem oder zwei Motoren angetrieben wird, zeichnet sich die MS-Serie durch ihr kompaktes Design ohne Leistungseinbu\u00dfen aus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60a1400 elementor-widget elementor-widget-heading\" data-id=\"60a1400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Zweiachsige Maschine mit Einzelmotor<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8e6976 elementor-widget elementor-widget-text-editor\" data-id=\"e8e6976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Einmotorige, zweiachsige Schreddermaschine, die auf Vielseitigkeit ausgelegt ist und verschiedene Aufgaben pr\u00e4zise bew\u00e4ltigen kann. Die nahtlose Integration des zweiachsigen Systems vereinfacht die Bedienung und gew\u00e4hrleistet gleichzeitig optimale Kontrolle. Ob in der Fertigung, Automatisierung oder in jeder anderen Branche, die MS-Serie erweist sich als zuverl\u00e4ssige L\u00f6sung f\u00fcr kleine Schredderaufgaben.<\/p><p>Zu den Hauptmerkmalen unserer Maschinen geh\u00f6ren eine robuste Konstruktion, intuitive Bedienelemente und ein platzsparendes Design. Der einzelne Motor, der beide Achsen antreibt, verbessert die Energieeffizienz und macht sie zu einer kosteng\u00fcnstigen Wahl. Insgesamt stellt die MS-Serie einen technologischen Fortschritt bei zweiachsigen Maschinen dar und bietet eine optimierte und zuverl\u00e4ssige L\u00f6sung f\u00fcr verschiedene industrielle Anwendungen.\u00a0<\/p><p>Anwendung: Obst, Gem\u00fcse, Speisereste und einige leichte Materialien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ff01dd elementor-widget elementor-widget-image\" data-id=\"3ff01dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"334\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/small-metal-shredder-from-bsgh-granulator-1024x427.jpg\" class=\"attachment-large size-large wp-image-59513\" alt=\"kleiner Metallschredder vom BSGH Granulator\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/small-metal-shredder-from-bsgh-granulator-1024x427.jpg 1024w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/small-metal-shredder-from-bsgh-granulator-300x125.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/small-metal-shredder-from-bsgh-granulator-768x320.jpg 768w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/small-metal-shredder-from-bsgh-granulator-600x250.jpg 600w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/small-metal-shredder-from-bsgh-granulator.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dff0f49 uael-header-sticky-no uael-border-yes elementor-widget elementor-widget-uael-table\" data-id=\"dff0f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div itemscope class=\"uael-table-wrapper\" itemtype=\"http:\/\/schema.org\/Table\">\n\t\t<table id=\"uael-table-id-dff0f49\" class=\"uael-text-break uael-column-rules uael-table\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\" data-responsive=\"no\">\n\t\t\t\t<thead>\n\t\t\t\t\t\t\t\t\t\t<tr class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"0\" class=\"sort-this elementor-repeater-item-a3e7013 uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Modell<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"1\" class=\"sort-this elementor-repeater-item-35fde8e uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-S300*180<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"2\" class=\"sort-this elementor-repeater-item-c72fc8a uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-S400*180<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"3\" class=\"sort-this elementor-repeater-item-1dd535c uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-S500*200<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"4\" class=\"sort-this elementor-repeater-item-28dcaf6 uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-S600*200<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t<\/thead>\n\t\t\t\t<tbody>\n\t\t\t<!-- ROWS -->\n\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b63f4d9\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Motor<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-31e23c7\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">3KW-4, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-84913a0\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">5,5KW-4, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-594842f\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">7,5KW-4, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-80b19c8\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">11KW-4, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3b8d7b9\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Untersetzungsgetriebe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c1bd611\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JK77, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3cc3e78\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JK87, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b251e4d\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JK97, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d48fb3c\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JK107, 1 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b25a8ca\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Schaltschrank<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c423535\" colspan=\"4\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">SPS-Steuerung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2792a3d\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Eingaberotation<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-5b840b3\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">16R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-33550a9\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">17R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0837f2c\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">15R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d250bbd\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">15R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-e8f082b\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Eingangsdrehmoment<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2f788f4\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">1696Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-69b4db5\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">2176Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-71fbe46\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">4574Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d0ae2b9\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">24960Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"6\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c8506de\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wellendurchmesser<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-411135f\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220575<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-cf132e8\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220585<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2749c95\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220590<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-4ed9b34\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220590<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"7\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-cbce49d\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Klingengr\u00f6\u00dfe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0b1e3f5\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205180*10<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3770e7e\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205180*10<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-a2c6d13\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205200*20<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-fb5488d\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205200*20<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"8\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d5107e6\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Klingen Menge<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-cb8296a\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">29 ST\u00dcCKE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-5e0b528\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">40 St\u00fcck<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b06c5c4\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">24 ST\u00dcCKE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-059f2e9\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">30 St\u00fcck<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"9\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-452718a\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">F\u00fctterungsgr\u00f6\u00dfe (ver\u00e4nderbar)<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b93791d\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">500*500*300<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-23794db\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">500*600*300<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-8fb5502\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">600*700*400<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-9b2dae6\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">940*680*500<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"10\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-08b2539\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Maschinengr\u00f6\u00dfe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-850fafa\" data-title=\"MS-S300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">1200*500*1300<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-606ff7d\" data-title=\"MS-S400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">1400*500*1450<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1d8bd5f\" data-title=\"MS-S500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">1600*600*1550<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b459e39\" data-title=\"MS-S600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">2000*660*1800<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t<\/tbody>\n\t<\/table>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-782fd85 elementor-widget elementor-widget-heading\" data-id=\"782fd85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Double Axis Machine With 2 Motors<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34d7232 elementor-widget elementor-widget-text-editor\" data-id=\"34d7232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Vergleich zu kleinen Zerkleinerern mit Doppelwelle und Einzelmotor ist der Zerkleinerer mit Doppelmotor leistungsst\u00e4rker und robuster. Anwendung: Kunststoff, Metallf\u00e4sser, Paletten oder andere Materialien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f6a360 elementor-widget elementor-widget-image\" data-id=\"7f6a360\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"334\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/twin-shaft-shredder-machine-with-double-motors-from-bsgh-granulator-1024x427.jpg\" class=\"attachment-large size-large wp-image-59514\" alt=\"Doppelwellen-Zerkleinerer mit Doppelmotoren von BSGH Granulator\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/twin-shaft-shredder-machine-with-double-motors-from-bsgh-granulator-1024x427.jpg 1024w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/twin-shaft-shredder-machine-with-double-motors-from-bsgh-granulator-300x125.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/twin-shaft-shredder-machine-with-double-motors-from-bsgh-granulator-768x320.jpg 768w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/twin-shaft-shredder-machine-with-double-motors-from-bsgh-granulator-600x250.jpg 600w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/01\/twin-shaft-shredder-machine-with-double-motors-from-bsgh-granulator.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b867672 uael-header-sticky-no uael-border-yes elementor-widget elementor-widget-uael-table\" data-id=\"b867672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div itemscope class=\"uael-table-wrapper\" itemtype=\"http:\/\/schema.org\/Table\">\n\t\t<table id=\"uael-table-id-b867672\" class=\"uael-text-break uael-column-rules uael-table\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\" data-responsive=\"no\">\n\t\t\t\t<thead>\n\t\t\t\t\t\t\t\t\t\t<tr class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"0\" class=\"sort-this elementor-repeater-item-a3e7013 uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Modell<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"1\" class=\"sort-this elementor-repeater-item-35fde8e uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-D300*180<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"2\" class=\"sort-this elementor-repeater-item-c72fc8a uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-D400*180<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"3\" class=\"sort-this elementor-repeater-item-1dd535c uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-D500*200<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"4\" class=\"sort-this elementor-repeater-item-28dcaf6 uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">MS-D600*200<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t<\/thead>\n\t\t\t\t<tbody>\n\t\t\t<!-- ROWS -->\n\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b63f4d9\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Motor<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-31e23c7\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">3KW-4, 2Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-84913a0\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">5,5KW-4, 2 S\u00e4tze<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-594842f\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">7,5KW-4, 2 S\u00e4tze<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-80b19c8\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">11KW-4, 2Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3b8d7b9\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Untersetzungsgetriebe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c1bd611\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JK77, 2er-Set<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3cc3e78\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JKA87, 2er-Set<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b251e4d\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JKA97, 2er-Set<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d48fb3c\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">JKA107, 2 Satz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b25a8ca\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Schaltschrank<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c423535\" colspan=\"4\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">SPS-Steuerung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2792a3d\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Eingaberotation<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-5b840b3\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">16R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-33550a9\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">17R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0837f2c\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">15R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d250bbd\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">15R\/M<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-e8f082b\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Eingangsdrehmoment<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2f788f4\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">3107Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-69b4db5\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">3952Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-71fbe46\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">8255Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d0ae2b9\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">24960Nm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"6\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-c8506de\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Wellendurchmesser<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-411135f\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220575<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-cf132e8\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220585<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2749c95\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220590<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-4ed9b34\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u220590<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"7\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-cbce49d\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Klingengr\u00f6\u00dfe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0b1e3f5\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205180*10<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-3770e7e\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205180*10<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-a2c6d13\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205200*20<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-fb5488d\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">\u2205200*20<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"8\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-d5107e6\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Klingen Menge<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-cb8296a\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">29 ST\u00dcCKE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-5e0b528\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">40 St\u00fcck<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b06c5c4\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">24 ST\u00dcCKE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-059f2e9\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">30 St\u00fcck<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"9\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-452718a\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Material\u00f6ffnungsgr\u00f6\u00dfe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b93791d\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">500*500*300<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-23794db\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">500*600*300<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-8fb5502\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">600*700*400<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-9b2dae6\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">940*680*500<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"10\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-08b2539\" data-title=\"Model\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Maschinengr\u00f6\u00dfe<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-850fafa\" data-title=\"MS-D300*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">1200*500*1300<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-606ff7d\" data-title=\"MS-D400*180\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">1400*500*1450<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1d8bd5f\" data-title=\"MS-D500*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">1600*600*1550<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-b459e39\" data-title=\"MS-D600*200\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">2000*660*1800<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t<\/tbody>\n\t<\/table>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4c438 elementor-widget elementor-widget-text-editor\" data-id=\"ae4c438\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Hinweis: Die oben genannten Daten sind nicht festgelegt. Wir erstellen sie f\u00fcr Sie gem\u00e4\u00df Ihren unterschiedlichen Anforderungen, wie z. B. Eingabekapazit\u00e4t, Ausgabegr\u00f6\u00dfe, Materialtypen usw. Kontaktieren Sie unseren Experten f\u00fcr weitere Einzelheiten.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eba5d1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6eba5d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjI3MDQ5IiwidG9nZ2xlIjpmYWxzZX0=\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">angenehme Beratung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e2b1905 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e2b1905\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f5f57e7\" data-id=\"6f5f57e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fe1d196 elementor-widget elementor-widget-heading\" data-id=\"3fe1d196\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">unsere ifat Messe und Kanton Messe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23b47626 elementor-widget elementor-widget-text-editor\" data-id=\"23b47626\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2 Mal Offline-Ausstellungen IFAT-Messe und 2 Mal Offline-Ausstellungen Canton-Messe<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fda0de5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7fda0de5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bcd9db3 elementor-skin-coverflow elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"5bcd9db3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;coverflow&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u5e7b\u706f\u7247\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"QQ\u56fe\u724720191209113933_proc (1)\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/QQ\u56fe\u724720191209113933_proc-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Gruppenfoto\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG_4845_proc.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"ifat Messe\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG_4857-scaled1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"IFAT\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG_4977-scaled1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"ifat\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG_4807_proc-scaled1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Hersteller von Doppelwellen-Zerkleinerermaschinen\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG20180516145202-scaled1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"IFAT Messe in Deutschland\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/QQ\u56fe\u724720180918154709_proc.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Kabelgranulator Qualit\u00e4t beweisen\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG_4977-scaled1-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"IMG_0385-skaliert\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG_0385-scaled-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"IMG_6374-skaliert\" style=\"background-image: url(&#039;https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG_6374-scaled-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00f3ximo\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a69c524 elementor-section-content-middle custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"3a69c524\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;pulse&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b1308b\" data-id=\"4b1308b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dbbe08f elementor-widget elementor-widget-heading\" data-id=\"1dbbe08f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Holen Sie sich noch heute den besten Preis.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-401f588 elementor-widget elementor-widget-text-editor\" data-id=\"401f588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sichern Sie sich jetzt das beste Angebot f\u00fcr unsere kleinen Metallzerkleinerer! Jetzt k\u00f6nnen Sie diese Zerkleinerer zu unglaublichen Preisen erhalten. Sie sind f\u00fcr ihre Zuverl\u00e4ssigkeit und gute Leistung bekannt. Jetzt ist der beste Zeitpunkt, um ein n\u00fctzliches Werkzeug f\u00fcr die Metallbearbeitung zu erwerben, ohne viel Geld auszugeben. Machen Sie gleich etwas, um dieses Angebot zu erhalten und das Beste aus Ihrem Geld herauszuholen. Kontaktieren Sie uns, um das beste Angebot f\u00fcr unsere kleinen Metallzerkleinerer zu erhalten!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3236e889\" data-id=\"3236e889\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22441803 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"22441803\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"58880\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"22441803\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Small Metal Shredder\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"58880\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-Mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tIhre Bed\u00fcrfnisse\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Ihre Bed\u00fcrfnisse\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Einreichen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb56acb elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb56acb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79097ccf elementor-invisible\" data-id=\"79097ccf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71a58f6b elementor-widget elementor-widget-heading\" data-id=\"71a58f6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Die Vorteile<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf5d27f elementor-widget elementor-widget-heading\" data-id=\"4cf5d27f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einige Punkte f\u00fcr kleine Metallschredder<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39aabfa7 elementor-widget elementor-widget-text-editor\" data-id=\"39aabfa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser kleiner Metallzerkleinerer ist klein, aber stark. Er ist flexibel und benutzerfreundlich und eignet sich f\u00fcr viele verschiedene Metallzerkleinerungssituationen mit geringem Wartungsaufwand.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23fa9b90 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"23fa9b90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bacterium\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAnpassbares Materialhandling\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDer kleine Metallschredder ist so konzipiert, dass er schnell und einfach eine Vielzahl von Metallabf\u00e4llen zerkleinern kann. Da er verschiedene Metalle zerkleinern kann, von Aluminium \u00fcber Kupfer bis hin zu Kunststoff, Holz usw., kann er in einer Vielzahl von Industrieumgebungen eingesetzt werden, beispielsweise auf Schrottpl\u00e4tzen und in Werkst\u00e4tten, die Metallgegenst\u00e4nde herstellen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f3ecc8 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"51f3ecc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-superpowers\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPlatzsparendes Design\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDieser Aktenvernichter wurde f\u00fcr kleine R\u00e4ume konzipiert und verf\u00fcgt \u00fcber eine hohe Zerkleinerungsleistung. Diese Funktion ist besonders hilfreich f\u00fcr kleinere Geb\u00e4ude oder Werkst\u00e4tten, die ihren Platz optimal nutzen m\u00fcssen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3acfedd2 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3acfedd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cubes\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tZuverl\u00e4ssige Zerkleinerungsleistung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDer Aktenvernichter verf\u00fcgt \u00fcber ein zuverl\u00e4ssiges System, das daf\u00fcr sorgt, dass Rohmaterialien gleichm\u00e4\u00dfig und gut zerkleinert werden. Dies ist sehr wichtig f\u00fcr Unternehmen, die eine gleichbleibende Zerkleinerungsqualit\u00e4t f\u00fcr das Recycling oder als Schritt vor dem n\u00e4chsten Schritt im Herstellungsprozess ben\u00f6tigen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ecfbd79\" data-id=\"1ecfbd79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40948606 elementor-widget elementor-widget-image\" data-id=\"40948606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/double-shaft-shredder-machine-manufacturer.jpg\" class=\"attachment-large size-large wp-image-56259\" alt=\"Hersteller von Doppelwellen-Zerkleinerermaschinen\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/double-shaft-shredder-machine-manufacturer.jpg 500w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/double-shaft-shredder-machine-manufacturer-300x300.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/double-shaft-shredder-machine-manufacturer-150x150.jpg 150w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/double-shaft-shredder-machine-manufacturer-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e08d045 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e08d045\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27f86b04\" data-id=\"27f86b04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5de9655 elementor-widget elementor-widget-heading\" data-id=\"5de9655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Was wir tun<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-701271b elementor-widget elementor-widget-text-editor\" data-id=\"701271b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Zerkleinerungsger\u00e4te von BSGH Granulator zielen haupts\u00e4chlich auf Maschinen guter Qualit\u00e4t ab. Unabh\u00e4ngig von den Klingen, der Welle, der Dichtung oder dem Getriebe verwenden wir die beste Qualit\u00e4t zum besten Preis-Leistungs-Verh\u00e4ltnis. Am h\u00e4ufigsten verwenden wir importierte H13-Materialien. Sie k\u00f6nnen auch bessere, teurere Klingen w\u00e4hlen, die wir individuell f\u00fcr Sie anpassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1bcaf23a animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"1bcaf23a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-69c6603b\" data-id=\"69c6603b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a26a81b elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1a26a81b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-pushed\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInnovatives Design f\u00fcr Vielseitigkeit\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUnsere kleinen Metallschredder sind mit neuen Designmerkmalen ausgestattet, die ihnen viele verschiedene Schneidarten erm\u00f6glichen. Dank ihrer Flexibilit\u00e4t k\u00f6nnen sie f\u00fcr eine Vielzahl von Aufgaben eingesetzt werden und verschiedene Arten von Metallabf\u00e4llen effektiv zerkleinern.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2fb55d81\" data-id=\"2fb55d81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-726ec6cd elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"726ec6cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-thumbs-up\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tStrenge Qualit\u00e4tsstandards\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBei der Herstellung unserer Aktenvernichter befolgen wir strenge Qualit\u00e4tsstandards. Jedes Ger\u00e4t durchl\u00e4uft zahlreiche Tests, um sicherzustellen, dass es einwandfrei funktioniert und lange h\u00e4lt. Dies garantiert eine zuverl\u00e4ssige und gleichbleibende Leistung.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6f6b9d33\" data-id=\"6f6b9d33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31716535 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"31716535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-picasa-1\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAnpassbare L\u00f6sungen f\u00fcr Kundenanforderungen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDa wir wissen, dass unsere Kunden unterschiedliche Bed\u00fcrfnisse haben, bieten wir Aktenvernichter an, die an spezifische Betriebsanforderungen angepasst werden k\u00f6nnen. Unsere Methode basiert darauf, Abl\u00e4ufe effizienter zu gestalten und die spezifischen Bed\u00fcrfnisse jedes Kunden zu erf\u00fcllen, indem wir sicherstellen, dass er einen Aktenvernichter erh\u00e4lt, der seinen Verarbeitungsanforderungen entspricht.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b6f2871 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b6f2871\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68eb4980\" data-id=\"68eb4980\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bfeb4e7 elementor-widget elementor-widget-heading\" data-id=\"6bfeb4e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum uns w\u00e4hlen?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e2fe7d3 elementor-widget elementor-widget-text-editor\" data-id=\"7e2fe7d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beauftragen Sie uns mit der Herstellung Ihres kleinen Metallschredders, denn wir sind Experten in der Herstellung flexibler, qualitativ hochwertiger Schredder, legen h\u00f6chste Wert auf Qualit\u00e4t und k\u00f6nnen ein breites Spektrum an Betriebsanforderungen pr\u00e4zise und zuverl\u00e4ssig erf\u00fcllen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3bf71f38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bf71f38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e291d2\" data-id=\"1e291d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bab16ea elementor-widget elementor-widget-heading\" data-id=\"3bab16ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i class=\"fa fa-user-o\"><\/i> Effektive Teamarbeit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c780452 elementor-widget elementor-widget-text-editor\" data-id=\"1c780452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Zusammenarbeit mit unserem Team ist unkompliziert und wir sorgen daf\u00fcr, dass Ihr kleiner Metallschredder mit Sorgfalt und Pr\u00e4zision perfekt gebaut wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7af11731\" data-id=\"7af11731\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d27ccc elementor-widget elementor-widget-heading\" data-id=\"8d27ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i class=\"fa fa-clock-o\"><\/i> 25+ Jahre Erfahrung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1418018f elementor-widget elementor-widget-text-editor\" data-id=\"1418018f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir stellen seit \u00fcber 25 Jahren kleine Metallzerkleinerer her und wissen daher besser als jeder andere, wie man sie herstellt. Wir versprechen beste Qualit\u00e4t und Leistung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c2ef626 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c2ef626\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-23a3b5b4\" data-id=\"23a3b5b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7036f7b2 elementor-widget elementor-widget-heading\" data-id=\"7036f7b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i class=\"fa fa-star-o\"><\/i> Hochtechnologiefabrik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1179515 elementor-widget elementor-widget-text-editor\" data-id=\"1179515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In unserer Werkstatt k\u00f6nnen Sie sehen, wie mithilfe modernster Technologie mit Pr\u00e4zision und modernsten Fertigungsmethoden hochwertige Kleinmetallzerkleinerer hergestellt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5546d1b2\" data-id=\"5546d1b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eaa0202 elementor-widget elementor-widget-heading\" data-id=\"3eaa0202\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i class=\"fa fa-handshake-o\"><\/i> Flexibler Zahlungsplan<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-503717a8 elementor-widget elementor-widget-text-editor\" data-id=\"503717a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Schauen Sie sich unsere flexiblen Zahlungsoptionen f\u00fcr den Kauf eines kleinen Metallschredders an. Diese Optionen sind auf Ihr Budget zugeschnitten und erleichtern den Kaufprozess.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd43ada elementor-widget elementor-widget-heading\" data-id=\"fd43ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">BSGH Granulator Markenkonzept<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d34dde elementor-widget elementor-widget-text-editor\" data-id=\"3d34dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>BSGH Granulator ist ein Maschinenbauunternehmen, das sich haupts\u00e4chlich mit der Forschung und Entwicklung, Herstellung und dem Vertrieb von Altmetallrecyclingmaschinen besch\u00e4ftigt. Wir halten stets an der Gesch\u00e4ftsphilosophie \u201eHerstellung hochwertiger Maschinen\u201c fest und setzen die Richtlinie \u201eNur die Kundenzufriedenheit kann uns erfolgreich machen\u201c um, indem wir ein junges, professionelles und hochwertiges Team bilden. Die von uns hergestellten Maschinen sind leistungsstark und haben eine stabile Leistung. BSGH Granulator h\u00f6rt sich die Meinungen der Kunden unvoreingenommen an. Wir verbessern st\u00e4ndig unsere Fertigungstechnologie und unser Servicebewusstsein und werden im Entwicklungsprozess st\u00e4rker.<\/p><p>\u00a0\u00a0\u00a0In Zukunft wird sich BSGH Granulator auf Produktdetails konzentrieren, weiterhin hart an der Produktqualit\u00e4t arbeiten und eine chinesische Marke mit guten Ums\u00e4tzen und gutem Ruf aufbauen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-162f4a54\" data-id=\"162f4a54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-238e518f elementor-widget elementor-widget-image\" data-id=\"238e518f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG20180516145202-scaled1.jpg\" class=\"attachment-large size-large wp-image-27832\" alt=\"Hersteller von Doppelwellen-Zerkleinerermaschinen\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG20180516145202-scaled1.jpg 768w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG20180516145202-scaled1-300x225.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/10\/IMG20180516145202-scaled1-600x450.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-765452e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"765452e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3893f4d5 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"3893f4d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-423ef0 elementor-widget elementor-widget-image\" data-id=\"423ef0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"600\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/D30\u53d1\u8d27111-2-500x600-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-34698\" alt=\"BS-D30 wird ausgeliefert\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/D30\u53d1\u8d27111-2-500x600-1.jpg 500w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/D30\u53d1\u8d27111-2-500x600-1-250x300.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73a5378b\" data-id=\"73a5378b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61a5b419 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"61a5b419\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Lass uns arbeiten<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b461087 elementor-widget elementor-widget-heading\" data-id=\"5b461087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">So erhalten Sie von uns kleine Metallschredder<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a079d5d elementor-widget elementor-widget-text-editor\" data-id=\"4a079d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kontaktieren Sie uns, wenn Sie einen kleinen Metallschneider ben\u00f6tigen. Wir k\u00f6nnen Ihnen bei Ihren Anforderungen helfen, indem wir Sie fachkundig beraten und den Kaufprozess vereinfachen.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a2fe284 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a2fe284\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7eab412f\" data-id=\"7eab412f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a8b1f26 elementor-widget elementor-widget-heading\" data-id=\"7a8b1f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-223765c7 elementor-widget__width-auto elementor-absolute e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"223765c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5bb732ae\" data-id=\"5bb732ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e3cf654 elementor-widget elementor-widget-icon-box\" data-id=\"7e3cf654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAnfrage und Beratung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWenn Sie Fragen oder Anliegen zu unseren Kleinmetallzerkleinerern haben, k\u00f6nnen Sie sich gerne an uns wenden. Wir beantworten diese gerne und bieten Ihnen eine bedarfsgerechte Hilfestellung.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5b3f1d6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b3f1d6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2aa5109\" data-id=\"2aa5109\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c6cf57 elementor-widget elementor-widget-heading\" data-id=\"3c6cf57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-545138cc elementor-widget__width-auto elementor-absolute e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"545138cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-47250c37\" data-id=\"47250c37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7373bfb3 elementor-widget elementor-widget-icon-box\" data-id=\"7373bfb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAnpassung und Angebot\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNehmen Sie Kontakt mit uns auf, um ein individuelles Angebot f\u00fcr kleine Metallschredder zu erhalten, die auf Ihre Bed\u00fcrfnisse und die Art und Weise, wie Sie Ihr Gesch\u00e4ft f\u00fchren, zugeschnitten sind.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e7977f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e7977f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2b321506\" data-id=\"2b321506\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-377dc284 elementor-widget elementor-widget-heading\" data-id=\"377dc284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6361160e elementor-widget__width-auto elementor-absolute e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6361160e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4c54b8d0\" data-id=\"4c54b8d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-488cac69 elementor-widget elementor-widget-icon-box\" data-id=\"488cac69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAuftragsbest\u00e4tigung und Fertigung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSobald wir Deine Bestellung best\u00e4tigt haben, beginnen wir mit der sorgf\u00e4ltigen Fertigung Deines kleinen Metallschneiders und sorgen daf\u00fcr, dass dieser p\u00fcnktlich und ohne Probleme bei Dir eintrifft.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-643ae902 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"643ae902\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-540c192d\" data-id=\"540c192d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dea5235 elementor-widget elementor-widget-heading\" data-id=\"1dea5235\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">04.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b9c5bea\" data-id=\"3b9c5bea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fd0e128 elementor-widget elementor-widget-icon-box\" data-id=\"7fd0e128\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLieferung und Kundendienst\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUnsere kleinen Metallschredder werden schnell geliefert und werden mit umfassender Kundenbetreuung nach dem Kauf geliefert, um sicherzustellen, dass die Kunden zufrieden sind und die Maschinen reibungslos funktionieren.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37e0a8cb elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37e0a8cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-299b9a9c\" data-id=\"299b9a9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-20e9c675 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20e9c675\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-599b80e2 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"599b80e2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e37cf3\" data-id=\"e37cf3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cb208a1 elementor-widget elementor-widget-heading\" data-id=\"3cb208a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Passen Sie Ihre kleine Metallschreddermaschine an<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19472147 elementor-button-align-start elementor-widget elementor-widget-form\" data-id=\"19472147\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"58880\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"19472147\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Small Metal Shredder\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"58880\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tIhr Name\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Ihr Name\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-Mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_3a07eb6 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3a07eb6\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tErz\u00e4hlen Sie mehr\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[field_3a07eb6]\" id=\"form-field-field_3a07eb6\" rows=\"4\" placeholder=\"Erz\u00e4hlen Sie mir hier mehr ...\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anfrage senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-248e60ca\" data-id=\"248e60ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c3e4675 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4c3e4675\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Machen Sie ein Angebot<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa7b4a6 elementor-widget elementor-widget-heading\" data-id=\"3fa7b4a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teilen Sie uns Ihren Bedarf an Schreddermaschinen mit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-413fe8ef elementor-widget elementor-widget-text-editor\" data-id=\"413fe8ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sagen Sie uns, welche Anforderungen Sie an einen Schredder stellen. Wir entwickeln ma\u00dfgeschneiderte Verarbeitungsl\u00f6sungen, die Ihnen dabei helfen, effizienter und effektiver zu recyceln.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7374b1b6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7374b1b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Whatsapp\/Viber: 008613772508206<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">E-Mail: coppergranulator@bsghrecycling.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Website: https:\/\/bsghgranulator.com\/<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>high efficiency small metal shredder Machine When working on a smaller scale, a small metal shredder machine is an important tool for processing different kinds of metal scraps and also other materials just as pallets, plastic, drums, and so on. Its small size makes it easy to fit in tight areas, and it&#8217;s a powerful [&hellip;]<\/p>","protected":false},"author":1,"featured_media":56262,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Small Metal Shredder - For Shredding Scrap Metals and Plastic","_seopress_titles_desc":"We offer a diverse range of metal shredders, with our small metal shredder standing out as the epitome of reliability and high quality. With a focus on...","_seopress_robots_index":"","_seopress_analysis_target_kw":"small metal shredder","footnotes":""},"class_list":["post-58880","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/pages\/58880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/comments?post=58880"}],"version-history":[{"count":3,"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/pages\/58880\/revisions"}],"predecessor-version":[{"id":111442,"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/pages\/58880\/revisions\/111442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/media\/56262"}],"wp:attachment":[{"href":"https:\/\/bsghgranulator.com\/de\/wp-json\/wp\/v2\/media?parent=58880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}