{"id":60881,"date":"2024-02-27T15:52:17","date_gmt":"2024-02-27T07:52:17","guid":{"rendered":"https:\/\/bsghgranulator.com\/?page_id=60881"},"modified":"2024-06-11T11:44:20","modified_gmt":"2024-06-11T03:44:20","slug":"cable-granulator-and-separator","status":"publish","type":"page","link":"https:\/\/bsghgranulator.com\/fr\/granulateur-et-separateur-de-cables\/","title":{"rendered":"Hot Selling Cable Granulator and Separator"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"60881\" class=\"elementor elementor-60881\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be1bd0b custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be1bd0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9433fe9\" data-id=\"9433fe9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-384d398f elementor-widget elementor-widget-heading\" data-id=\"384d398f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">machine de granulation et de s\u00e9paration de c\u00e2bles<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f8cd86 elementor-widget elementor-widget-text-editor\" data-id=\"25f8cd86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les granulateurs et s\u00e9parateurs de c\u00e2bles BSGH r\u00e9volutionnent le secteur du recyclage des c\u00e2bles usag\u00e9s gr\u00e2ce \u00e0 une technologie de pointe. Nos machines sont sp\u00e9cialis\u00e9es dans la s\u00e9paration efficace du cuivre ou de l&#039;aluminium pr\u00e9cieux des c\u00e2bles ou fils usag\u00e9s. Elles offrent un rendement \u00e9lev\u00e9, un rendement \u00e9lev\u00e9 et une excellente qualit\u00e9, r\u00e9pondant \u00e0 divers besoins de recyclage.<\/p><p>Nous proposons trois principaux types de granulateurs et s\u00e9parateurs de c\u00e2bles, selon leur capacit\u00e9 de traitement\u00a0: gros d\u00e9bit, d\u00e9bit moyen et petit d\u00e9bit. Pour les clients dont la demande de traitement augmente, les machines \u00e0 petit d\u00e9bit peuvent \u00eatre \u00e9quip\u00e9es d&#039;\u00e9quipements suppl\u00e9mentaires. Nos mod\u00e8les phares garantissent des performances et une adaptabilit\u00e9 optimales pour toutes les op\u00e9rations de recyclage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e240a71 elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"3e240a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjI3MDQ5IiwidG9nZ2xlIjpmYWxzZX0=\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-302f12e\" data-id=\"302f12e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40067889 elementor-widget elementor-widget-video\" data-id=\"40067889\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/TGZLWLPnNQM&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2c0fca custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2c0fca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;zigzag&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1800 5.8\" preserveaspectratio=\"none\">\n  <path class=\"elementor-shape-fill\" d=\"M5.4.4l5.4 5.3L16.5.4l5.4 5.3L27.5.4 33 5.7 38.6.4l5.5 5.4h.1L49.9.4l5.4 5.3L60.9.4l5.5 5.3L72 .4l5.5 5.3L83.1.4l5.4 5.3L94.1.4l5.5 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.4 5.3L161 .4l5.4 5.3L172 .4l5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.5 5.3L261 .4l5.4 5.3L272 .4l5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.7-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.4h.2l5.6-5.4 5.5 5.3L361 .4l5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.7-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.6-5.4 5.5 5.3L461 .4l5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1L550 .4l5.4 5.3L561 .4l5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2L650 .4l5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2L750 .4l5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.7-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.4h.2L850 .4l5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.4 5.3 5.7-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.7-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.4 5.3 5.7-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.7-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.7-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.4h.2l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.7-5.4 5.4 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.5 5.4h.1l5.6-5.4 5.5 5.3 5.6-5.3 5.5 5.3 5.6-5.3 5.4 5.3 5.7-5.3 5.4 5.3 5.6-5.3 5.5 5.4V0H-.2v5.8z\"\/>\n<\/svg>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-055b020\" data-id=\"055b020\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41bf983 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41bf983\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b45d804\" data-id=\"b45d804\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1324f6e elementor-widget elementor-widget-image\" data-id=\"1324f6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bsghgranulator.com\/fr\/machine-de-granulation-de-cables-haut-de-gamme-serie-n\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/copper-granulators-BS-F3000\u7f8e\u5316-1-300x250.jpg\" class=\"attachment-medium size-medium wp-image-31609\" alt=\"Granulateur de cuivre BS-F3000\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/copper-granulators-BS-F3000\u7f8e\u5316-1-300x250.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/copper-granulators-BS-F3000\u7f8e\u5316-1.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c856f45 elementor-widget elementor-widget-text-editor\" data-id=\"c856f45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La machine de granulation et de s\u00e9paration de c\u00e2bles de grande capacit\u00e9 vise une capacit\u00e9 de 800 kg\/h \u00e0 2 t\/h.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-43297df\" data-id=\"43297df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36f0a1c elementor-widget elementor-widget-image\" data-id=\"36f0a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bsghgranulator.com\/fr\/broyeur-de-cuivre-serie-d\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/N130-33\u7f8e\u5316-300x250.jpg\" class=\"attachment-medium size-medium wp-image-31801\" alt=\"Destructeur de c\u00e2bles en cuivre BS-N130\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/N130-33\u7f8e\u5316-300x250.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/N130-33\u7f8e\u5316.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a225e elementor-widget elementor-widget-text-editor\" data-id=\"46a225e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La machine de granulation et de s\u00e9paration de c\u00e2bles de capacit\u00e9 moyenne vise une capacit\u00e9 de 300 kg\/h \u00e0 800 kg\/h.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dfb0976\" data-id=\"dfb0976\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82687ee elementor-widget elementor-widget-image\" data-id=\"82687ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bsghgranulator.com\/fr\/petits-hachoirs-a-fil\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/D20\u4f20\u9001\u5e26\u78c1\u9009-9\u7f8e\u5316-300x250.jpg\" class=\"attachment-medium size-medium wp-image-31834\" alt=\"Machine \u00e0 hacher le cuivre de petite capacit\u00e9 de BSGH\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/D20\u4f20\u9001\u5e26\u78c1\u9009-9\u7f8e\u5316-300x250.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2022\/11\/D20\u4f20\u9001\u5e26\u78c1\u9009-9\u7f8e\u5316.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47c55c1 elementor-widget elementor-widget-text-editor\" data-id=\"47c55c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La machine de granulation et de s\u00e9paration de c\u00e2bles de petite capacit\u00e9 vise une capacit\u00e9 de 40 kg\/h \u00e0 300 kg\/h.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-328522c custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"328522c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eda9167\" data-id=\"eda9167\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe74a47 elementor-widget elementor-widget-heading\" data-id=\"fe74a47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">vid\u00e9os sur le traitement de diff\u00e9rents types de c\u00e2bles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da9fbaf elementor-widget elementor-widget-text-editor\" data-id=\"da9fbaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre machine de granulation et de s\u00e9paration de c\u00e2bles peut traiter presque tous les types de c\u00e2bles de rebut sur le march\u00e9, tels que les fils automobiles, les fils carr\u00e9s, les c\u00e2bles mixtes, les c\u00e2bles d&#039;alimentation, les fils de t\u00e9l\u00e9communication, etc.\u00a0\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88c0472 e-tabs-view-vertical elementor-layout-end elementor-widget elementor-widget-video-playlist\" data-id=\"88c0472\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;playlist_title&quot;:&quot;Playlist&quot;,&quot;tabs&quot;:[{&quot;title&quot;:&quot;Car Harness Wire Recycling: 300~500kg\\\/h Efficient Copper Recovery&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/z8bP83xINSo&quot;,&quot;duration&quot;:&quot;0:57&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/z8bP83xINSo\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;8d1f5f9&quot;,&quot;vimeo_url&quot;:null,&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null},{&quot;title&quot;:&quot;Full Configuration BS-D30 Wire Recycling Machine|Copper Wire Separator Machine With 300kg\\\/h Capacity&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/W-g1WLKhzJY&quot;,&quot;duration&quot;:&quot;0:31&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/W-g1WLKhzJY\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;4f67389&quot;,&quot;vimeo_url&quot;:null,&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null},{&quot;title&quot;:&quot;Malaysia Customer&#039;s Copper Wire Recycling Machine (300kg\\\/h) | High-Profit Wire Recycling&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/44n-BV-E3Ng&quot;,&quot;duration&quot;:&quot;1:01&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/44n-BV-E3Ng\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;d7120c2&quot;,&quot;vimeo_url&quot;:null,&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null},{&quot;title&quot;:&quot;Your Best Cable Recycling Machine | 200kg\\\/h Scrap Copper Wire Recycling Granulator Machinery&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/m1Qz7ZAt_Zc&quot;,&quot;duration&quot;:&quot;1:02&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/m1Qz7ZAt_Zc\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;vimeo_url&quot;:null,&quot;_id&quot;:&quot;d75999f&quot;,&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null},{&quot;_id&quot;:&quot;68a13fa&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/-psS9Om0s9g&quot;,&quot;vimeo_url&quot;:null,&quot;title&quot;:&quot;Japan Customer&#039;s Feedback Video Of Wire Recycling Machine BS-N125 In Processing Square Wires&quot;,&quot;duration&quot;:&quot;1:08&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/-psS9Om0s9g\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null},{&quot;_id&quot;:&quot;5d07228&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/YiWXS0miA30&quot;,&quot;vimeo_url&quot;:null,&quot;title&quot;:&quot;Pakistan Feedback Video of 70kg\\\/h Cable Granulator Machine In Recycling Waste Car Cables&quot;,&quot;duration&quot;:&quot;0:37&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/YiWXS0miA30\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null},{&quot;_id&quot;:&quot;380be2d&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/xVOwQoodwzA&quot;,&quot;vimeo_url&quot;:null,&quot;title&quot;:&quot;ACSR Cable Recycling Line In Processing Thick Armor Wire | Separating Copper From Scrap Cables&quot;,&quot;duration&quot;:&quot;1:30&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/xVOwQoodwzA\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null},{&quot;_id&quot;:&quot;32bb890&quot;,&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/7qoJm1mI0tY&quot;,&quot;vimeo_url&quot;:null,&quot;title&quot;:&quot;Best Performance Copper Wire Granulator BS-N130 | 400~700kg\\\/h Wire Recycling Machine #recycle&quot;,&quot;duration&quot;:&quot;0:38&quot;,&quot;thumbnail&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/img.youtube.com\\\/vi\\\/7qoJm1mI0tY\\\/maxresdefault.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;type&quot;:&quot;youtube&quot;,&quot;is_external_url&quot;:null,&quot;hosted_url&quot;:null,&quot;external_url&quot;:null,&quot;section_html_tag&quot;:null,&quot;video_html_tag&quot;:&quot;h4&quot;,&quot;inner_tab_is_content_visible&quot;:&quot;&quot;,&quot;inner_tab_content_1&quot;:null,&quot;inner_tab_content_2&quot;:null}],&quot;inner_tab_title_1&quot;:&quot;Tab #1&quot;,&quot;inner_tab_title_2&quot;:&quot;Tab #2&quot;}\" data-widget_type=\"video-playlist.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"e-tabs\" role=\"region\" aria-labelledby=\"e-playlist-88c0472\">\n\t\t\t<div class=\"e-tabs-main-area\">\n\t\t\t\t<div class=\"e-tabs-wrapper\">\n\t\t\t\t\t<div class=\"e-tabs-header\">\n\t\t\t\t\t\t<h2 class=\"e-tabs-title\" id=\"e-playlist-88c0472\">Liste de lecture<\/h2>\n\t\t\t\t\t\t<div class=\"e-tabs-header-right-side\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tabs-videos-count\">8 Vid\u00e9os<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"e-tabs-toggle-videos-display-button rotate-down eicon-caret-down\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"e-tabs-items-wrapper\">\n\t\t\t\t\t\t<div class=\"e-tabs-items\" role=\"tablist\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1431\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-tab-content-1431\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/z8bP83xINSo\/maxresdefault.jpg\" alt=\"Recyclage des c\u00e2bles de faisceau de c\u00e2bles automobiles\u00a0: r\u00e9cup\u00e9ration efficace du cuivre de 300 \u00e0 500\u00a0kg\/h\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Recyclage des c\u00e2bles de faisceau de c\u00e2bles automobiles\u00a0: r\u00e9cup\u00e9ration efficace du cuivre de 300 \u00e0 500\u00a0kg\/h<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">0:57<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1432\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-tab-content-1432\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/W-g1WLKhzJY\/maxresdefault.jpg\" alt=\"Machine de recyclage de fils BS-D30 \u00e0 configuration compl\u00e8te | S\u00e9parateur de fils de cuivre d&#039;une capacit\u00e9 de 300 kg\/h\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Machine de recyclage de fils BS-D30 \u00e0 configuration compl\u00e8te | S\u00e9parateur de fils de cuivre d&#039;une capacit\u00e9 de 300 kg\/h<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">0:31<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1433\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-tab-content-1433\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/44n-BV-E3Ng\/maxresdefault.jpg\" alt=\"Machine de recyclage de fils de cuivre (300 kg\/h) d&#039;un client malaisien | Recyclage de fils \u00e0 haut rendement\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Machine de recyclage de fils de cuivre (300 kg\/h) d&#039;un client malaisien | Recyclage de fils \u00e0 haut rendement<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">1:01<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1434\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-tab-content-1434\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/m1Qz7ZAt_Zc\/maxresdefault.jpg\" alt=\"Votre meilleure machine de recyclage de c\u00e2bles | Machine de granulation pour le recyclage des fils de cuivre usag\u00e9s (200 kg\/h)\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Votre meilleure machine de recyclage de c\u00e2bles | Machine de granulation pour le recyclage des fils de cuivre usag\u00e9s (200 kg\/h)<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">1:02<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1435\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-tab-content-1435\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/-psS9Om0s9g\/maxresdefault.jpg\" alt=\"Vid\u00e9o de retour d&#039;exp\u00e9rience d&#039;un client japonais sur la machine de recyclage de fils BS-N125 pour le traitement de fils carr\u00e9s\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Vid\u00e9o de retour d&#039;exp\u00e9rience d&#039;un client japonais sur la machine de recyclage de fils BS-N125 pour le traitement de fils carr\u00e9s<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">1:08<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1436\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-tab-content-1436\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/YiWXS0miA30\/maxresdefault.jpg\" alt=\"Vid\u00e9o de retour d&#039;exp\u00e9rience sur la granulation de c\u00e2bles de 70 kg\/h au Pakistan, utilis\u00e9e pour le recyclage des c\u00e2bles automobiles usag\u00e9s.\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Vid\u00e9o de retour d&#039;exp\u00e9rience sur la granulation de c\u00e2bles de 70 kg\/h au Pakistan, utilis\u00e9e pour le recyclage des c\u00e2bles automobiles usag\u00e9s.<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">0:37<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1437\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-tab-content-1437\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/xVOwQoodwzA\/maxresdefault.jpg\" alt=\"Ligne de recyclage de c\u00e2bles ACSR pour le traitement des fils blind\u00e9s \u00e9pais | S\u00e9paration du cuivre des c\u00e2bles usag\u00e9s\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Ligne de recyclage de c\u00e2bles ACSR pour le traitement des fils blind\u00e9s \u00e9pais | S\u00e9paration du cuivre des c\u00e2bles usag\u00e9s<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">1:30<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-title-1438\" class=\"e-tab-title e-tab-desktop-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-tab-content-1438\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-tab-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/7qoJm1mI0tY\/maxresdefault.jpg\" alt=\"Granulateur de fil de cuivre hautes performances BS-N130 | Machine de recyclage de fil 400 \u00e0 700 kg\/h #recycle\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-play\"><i aria-hidden=\"true\" class=\"fas fa-play-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-watched\"><i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"e-tab-title-text\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\">Granulateur de fil de cuivre hautes performances BS-N130 | Machine de recyclage de fil 400 \u00e0 700 kg\/h #recycle<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"e-tab-duration\">0:38<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"shadow shadow-top\" aria-hidden=\"true\"><\/div>\n\t\t\t\t\t\t<div class=\"shadow shadow-bottom\" aria-hidden=\"true\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"e-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1431\" class=\"e-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1431\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/z8bP83xINSo\" data-video-type=\"youtube\" data-video-title=\"Car Harness Wire Recycling: 300~500kg\/h Efficient Copper Recovery\" data-video-duration=\"0:57\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1432\" class=\"e-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1432\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/W-g1WLKhzJY\" data-video-type=\"youtube\" data-video-title=\"Full Configuration BS-D30 Wire Recycling Machine|Copper Wire Separator Machine With 300kg\/h Capacity\" data-video-duration=\"0:31\" hidden=\"hidden\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1433\" class=\"e-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1433\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/44n-BV-E3Ng\" data-video-type=\"youtube\" data-video-title=\"Malaysia Customer&#039;s Copper Wire Recycling Machine (300kg\/h) | High-Profit Wire Recycling\" data-video-duration=\"1:01\" hidden=\"hidden\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1434\" class=\"e-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1434\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/m1Qz7ZAt_Zc\" data-video-type=\"youtube\" data-video-title=\"Your Best Cable Recycling Machine | 200kg\/h Scrap Copper Wire Recycling Granulator Machinery\" data-video-duration=\"1:02\" hidden=\"hidden\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1435\" class=\"e-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1435\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/-psS9Om0s9g\" data-video-type=\"youtube\" data-video-title=\"Japan Customer&#039;s Feedback Video Of Wire Recycling Machine BS-N125 In Processing Square Wires\" data-video-duration=\"1:08\" hidden=\"hidden\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1436\" class=\"e-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1436\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/YiWXS0miA30\" data-video-type=\"youtube\" data-video-title=\"Pakistan Feedback Video of 70kg\/h Cable Granulator Machine In Recycling Waste Car Cables\" data-video-duration=\"0:37\" hidden=\"hidden\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1437\" class=\"e-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1437\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/xVOwQoodwzA\" data-video-type=\"youtube\" data-video-title=\"ACSR Cable Recycling Line In Processing Thick Armor Wire | Separating Copper From Scrap Cables\" data-video-duration=\"1:30\" hidden=\"hidden\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"e-tab-content-1438\" class=\"e-tab-content elementor-clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"e-tab-title-1438\" tabindex=\"0\" data-video-url=\"https:\/\/youtu.be\/7qoJm1mI0tY\" data-video-type=\"youtube\" data-video-title=\"Best Performance Copper Wire Granulator BS-N130 | 400~700kg\/h Wire Recycling Machine #recycle\" data-video-duration=\"0:38\" hidden=\"hidden\">\n\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"e-tabs-inner-tabs\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-490592fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"490592fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4451df83 elementor-invisible\" data-id=\"4451df83\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23f102d elementor-widget elementor-widget-counter\" data-id=\"23f102d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Ann\u00e9es d&#039;exp\u00e9rience<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"25\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-263c8bf4 elementor-widget elementor-widget-image\" data-id=\"263c8bf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"291\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/10\/BSGH-Factory-1024x373.jpg\" class=\"attachment-large size-large wp-image-52923\" alt=\"Usine BSGH\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/10\/BSGH-Factory-1024x373.jpg 1024w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/10\/BSGH-Factory-300x109.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/10\/BSGH-Factory-768x280.jpg 768w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/10\/BSGH-Factory-1536x560.jpg 1536w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/10\/BSGH-Factory-600x219.jpg 600w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/10\/BSGH-Factory.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fd2b323 elementor-invisible\" data-id=\"fd2b323\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29766c9d elementor-widget elementor-widget-heading\" data-id=\"29766c9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">\u00c0 propos du granulateur BSGH<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1d42d5 elementor-widget elementor-widget-heading\" data-id=\"4c1d42d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quelle est l&#039;application de la machine de granulation et de s\u00e9paration de c\u00e2bles BSGH ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e2d75f elementor-widget elementor-widget-text-editor\" data-id=\"1e2d75f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les fils usag\u00e9s, tels que les fils carr\u00e9s, les fils blind\u00e9s, les fils jumel\u00e9s, les fils t\u00e9l\u00e9phoniques, les c\u00e2bles de communication et les c\u00e2bles automobiles, contiennent g\u00e9n\u00e9ralement du cuivre pr\u00e9cieux et r\u00e9utilisable. Nos machines sont con\u00e7ues pour recycler le cuivre, offrant une qualit\u00e9 \u00e9lev\u00e9e, de faibles pertes et un rendement \u00e9lev\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b6fd2 elementor-widget elementor-widget-image\" data-id=\"c5b6fd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"460\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/02\/various-types-of-scrap-cables.jpg\" class=\"attachment-large size-large wp-image-61745\" alt=\"\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/02\/various-types-of-scrap-cables.jpg 600w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2024\/02\/various-types-of-scrap-cables-300x230.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d6028f8 elementor-reverse-tablet elementor-reverse-mobile custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d6028f8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3adb96fe elementor-invisible\" data-id=\"3adb96fe\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64ec5263 elementor-widget elementor-widget-heading\" data-id=\"64ec5263\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Pourquoi nous choisir<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592bd6d0 elementor-widget elementor-widget-heading\" data-id=\"592bd6d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">De quoi est compos\u00e9e la machine ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5adb67a3 elementor-widget elementor-widget-text-editor\" data-id=\"5adb67a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre granulateur et s\u00e9parateur de c\u00e2bles est compos\u00e9 de diff\u00e9rents \u00e9l\u00e9ments formant une structure globale. Ce type de structure facilite l&#039;installation et le d\u00e9bogage. Les clients peuvent \u00e9galement assembler les composants de la machine. L&#039;alimentation simultan\u00e9e, combin\u00e9e \u00e0 la collaboration multi-machines, assure une grande efficacit\u00e9 et une rentabilit\u00e9 \u00e9lev\u00e9e pour les clients.<\/p><p><strong><b>S<\/b><\/strong><strong><b>d\u00e9chiqueter<\/b><\/strong><strong><b>er\/Granulateur<\/b><\/strong>Placez les fils usag\u00e9s et ils seront coup\u00e9s en morceaux plus courts. Contrairement aux broyeurs \u00e0 double arbre du march\u00e9, qui permettent de comprimer plus facilement le cuivre et l&#039;aluminium, nous avons am\u00e9lior\u00e9 notre broyeur pour les raccourcir et \u00e9viter ainsi le probl\u00e8me mentionn\u00e9 ci-dessus.<\/p><p><strong><b>Broyeur:<\/b><\/strong>\u00a0\u00a0Le concasseur coupera les c\u00e2bles en morceaux plus petits.<\/p><p><strong><b>S\u00e9parateur d&#039;air<\/b><\/strong>Le principe du s\u00e9parateur d&#039;air repose sur la diff\u00e9rence de densit\u00e9 entre le m\u00e9tal et le plastique. Si ces particules rencontrent simultan\u00e9ment le flux d&#039;air sous l&#039;effet des vibrations, elles seront s\u00e9par\u00e9es en raison de leurs densit\u00e9s diff\u00e9rentes et se dirigeront vers des sorties diff\u00e9rentes. La vitesse et l&#039;angle du vent influencent \u00e9galement l&#039;effet de s\u00e9paration.<\/p><p><strong><b>Table vibrante<\/b><\/strong>La table vibrante coop\u00e8re toujours avec le s\u00e9parateur d&#039;air. Tous deux contribuent \u00e0 la s\u00e9paration du cuivre et du plastique. La fr\u00e9quence et l&#039;angle d&#039;inclinaison de la table vibrante influencent la s\u00e9paration.<\/p><p><strong><b>S\u00e9parateur magn\u00e9tique<\/b><\/strong>:Lorsque les morceaux de fil de cuivre traversent le s\u00e9parateur magn\u00e9tique, le fer sera attir\u00e9 vers les rouleaux par la force magn\u00e9tique.<\/p><p><strong><b>S\u00e9paration \u00e9lectrostatique<\/b><\/strong><strong><b>\uff1a<\/b><\/strong>La s\u00e9paration \u00e9lectrostatique permet de s\u00e9parer le plastique du m\u00e9tal gr\u00e2ce \u00e0 la diff\u00e9rence de charge \u00e9lectrique. Si vos fils de ferraille sont tr\u00e8s encombrants ou d&#039;un diam\u00e8tre assez fin, comme du fil de laine, nous vous conseillons d&#039;installer ce dispositif.<\/p><p><strong><b>Collecte de poussi\u00e8re<\/b><\/strong>:Il absorbe la poussi\u00e8re et prot\u00e8ge l&#039;environnement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-294865ef\" data-id=\"294865ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10ca1819 elementor-widget elementor-widget-image\" data-id=\"10ca1819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"770\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/cable-recycling-line-plant-overviews.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-57845\" alt=\"aper\u00e7us des installations de recyclage de c\u00e2bles\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/cable-recycling-line-plant-overviews.jpg 1300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/cable-recycling-line-plant-overviews-300x178.jpg 300w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/cable-recycling-line-plant-overviews-1024x607.jpg 1024w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/cable-recycling-line-plant-overviews-768x455.jpg 768w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/12\/cable-recycling-line-plant-overviews-600x355.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c352455 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c352455\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ff194ad\" data-id=\"1ff194ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12e2bf57 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"12e2bf57\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59cb6c1d\" data-id=\"59cb6c1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e011688 elementor-widget elementor-widget-video\" data-id=\"e011688\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/zWYfB1h4J2E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-256a7025\" data-id=\"256a7025\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45b68a6 elementor-widget elementor-widget-heading\" data-id=\"45b68a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">comment fonctionne la machine ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ea24b2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0ea24b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac9e38 elementor-widget elementor-widget-text-editor\" data-id=\"2ac9e38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#039;ensemble du processus est automatis\u00e9. L&#039;op\u00e9rateur n&#039;a qu&#039;\u00e0 placer les fils ou c\u00e2bles usag\u00e9s sur le convoyeur. Le mat\u00e9riau entre ensuite dans le concasseur par ce convoyeur. Il est d&#039;abord broy\u00e9, puis s\u00e9par\u00e9 par un s\u00e9parateur d&#039;air et une table vibrante. Enfin, le produit fini est transport\u00e9 vers la sortie. L&#039;ensemble du processus n\u00e9cessite peu de main-d&#039;\u0153uvre, ce qui permet de r\u00e9duire les co\u00fbts de main-d&#039;\u0153uvre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ae691d3 elementor-widget elementor-widget-heading\" data-id=\"4ae691d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">entretien lors de l&#039;utilisation du granulateur et du s\u00e9parateur de c\u00e2bles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-698201b7 elementor-widget elementor-widget-text-editor\" data-id=\"698201b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Parfois, m\u00eame une machine relativement r\u00e9cente ne fonctionne pas \u00e0 plein rendement. En effet, elle doit \u00eatre utilis\u00e9e correctement et n\u00e9cessite un entretien r\u00e9gulier pour garantir des performances optimales. Les conseils suivants vous aideront \u00e0 conna\u00eetre et \u00e0 entretenir votre machine.<\/p><ol><li>Les paliers principaux du broyeur, du concasseur et des s\u00e9parateurs doivent \u00eatre remplis de beurre r\u00e9sistant aux hautes temp\u00e9ratures tous les trois mois.<\/li><li>Le palier principal du s\u00e9parateur et les paliers excentriques des deux c\u00f4t\u00e9s doivent \u00eatre remplis de beurre r\u00e9sistant aux hautes temp\u00e9ratures tous les quatre mois.<\/li><li>Le palier principal de la machine \u00e9lectrostatique doit \u00eatre rempli de beurre haute temp\u00e9rature une fois par an.<\/li><li>Si la machine fonctionne en continu tous les jours sans interruption, elle sera endommag\u00e9e. Si votre volume de traitement est important et n\u00e9cessite un fonctionnement continu, vous pouvez faire une pause de 20 minutes toutes les quatre heures de fonctionnement.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56cba4ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56cba4ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e13791f elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"4e13791f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bf7844b elementor-widget elementor-widget-image\" data-id=\"5bf7844b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/02\/01.jpg\" class=\"attachment-full size-full wp-image-43854\" alt=\"Commentaires de nos clients australiens\" srcset=\"https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/02\/01.jpg 400w, https:\/\/bsghgranulator.com\/wp-content\/uploads\/2023\/02\/01-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45b7f36\" data-id=\"45b7f36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b3854b6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3b3854b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Travaillons<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65788a6b elementor-widget elementor-widget-heading\" data-id=\"65788a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">que ferons-nous une fois la commande confirm\u00e9e ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4bae5480 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bae5480\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33d7e1ee\" data-id=\"33d7e1ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bb28e4e elementor-widget elementor-widget-heading\" data-id=\"6bb28e4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7453b30b elementor-widget__width-auto elementor-absolute e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7453b30b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b4d0136\" data-id=\"5b4d0136\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70766c0c elementor-widget elementor-widget-icon-box\" data-id=\"70766c0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProduction de machines\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUne fois la commande confirm\u00e9e, nous contacterons notre service production pour lancer la production. Notre processus de production est efficace, rigoureux et chaque d\u00e9tail est soigneusement con\u00e7u et v\u00e9rifi\u00e9. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ae40d82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ae40d82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-28c0e1d6\" data-id=\"28c0e1d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-178ba789 elementor-widget elementor-widget-heading\" data-id=\"178ba789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-685ecd6d elementor-widget__width-auto elementor-absolute e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"685ecd6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-47377b8d\" data-id=\"47377b8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32f6b4dc elementor-widget elementor-widget-icon-box\" data-id=\"32f6b4dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\texp\u00e9dition et livraison\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUne fois la production de la machine termin\u00e9e et tous les paiements arriv\u00e9s, nous organiserons l&#039;emballage et l&#039;exp\u00e9dition d\u00e8s que possible. Nous pr\u00eaterons \u00e9galement attention aux informations de transport en temps opportun pour nous assurer que la machine arrive en toute s\u00e9curit\u00e9.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c0dfedc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c0dfedc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7fd9f02c\" data-id=\"7fd9f02c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cb560da elementor-widget elementor-widget-heading\" data-id=\"2cb560da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71e27df1 elementor-widget__width-auto elementor-absolute e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"71e27df1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1044d82\" data-id=\"1044d82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dd7ca1b elementor-widget__width-initial elementor-widget elementor-widget-icon-box\" data-id=\"2dd7ca1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tservice apr\u00e8s-vente soign\u00e9\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUne fois la transaction conclue, nos services ne s&#039;arr\u00eatent pas l\u00e0. Nous offrons un service apr\u00e8s-vente attentionn\u00e9 et rapide, et r\u00e9pondons \u00e0 toutes vos questions en ligne. Si votre probl\u00e8me ne peut \u00eatre r\u00e9solu en ligne, nous intervenons \u00e9galement sur place.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f8fa442 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f8fa442\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e3e126d\" data-id=\"3e3e126d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d5890a8 elementor-widget elementor-widget-heading\" data-id=\"4d5890a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">votre usine de machines de granulation et de s\u00e9paration de c\u00e2bles<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf84b47 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4bf84b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a7f233 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a7f233\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-821958e\" data-id=\"821958e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f8edc96 elementor-widget elementor-widget-heading\" data-id=\"1f8edc96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210dd72d elementor-widget elementor-widget-toggle\" data-id=\"210dd72d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5541\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5541\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Combien de temps faut-il g\u00e9n\u00e9ralement pour obtenir votre granulateur et s\u00e9parateur de c\u00e2bles ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5541\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5541\"><p>Notre d\u00e9lai de livraison habituel est d&#039;environ 20 \u00e0 30 jours, mais il peut varier en fonction de la taille, de la puissance et d&#039;autres d\u00e9tails de la commande. Pour conna\u00eetre la date exacte, veuillez contacter notre service client.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5542\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-5542\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Votre \u00e9quipement peut-il \u00eatre exp\u00e9di\u00e9 dans d\u2019autres pays ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5542\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-5542\"><p>Nous pouvons exp\u00e9dier partout dans le monde et nous pouvons \u00e9galement vous aider \u00e0 organiser l&#039;exp\u00e9dition et \u00e0 garantir la livraison de vos colis dans les d\u00e9lais. Les d\u00e9lais de livraison et les frais suppl\u00e9mentaires peuvent varier selon la destination du colis. N&#039;h\u00e9sitez pas \u00e0 nous contacter pour plus d&#039;informations.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5543\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-5543\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel type d&#039;aide existe-t-il pour le granulateur et le s\u00e9parateur de c\u00e2bles apr\u00e8s la vente ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5543\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-5543\"><p>Apr\u00e8s la vente, nous proposons une assistance technique, un d\u00e9pannage et des conseils pour l&#039;entretien courant. Nous nous engageons \u00e0 maintenir votre \u00e9quipement en parfait \u00e9tat de fonctionnement gr\u00e2ce \u00e0 des syst\u00e8mes d&#039;aide r\u00e9actifs.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5544\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-5544\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les pi\u00e8ces neuves sont-elles faciles \u00e0 trouver\u00a0? Sinon, comment les obtenir\u00a0?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5544\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-5544\"><p>Bien entendu, nous disposons d&#039;un stock de pi\u00e8ces d\u00e9tach\u00e9es n\u00e9cessaires, rapidement rempla\u00e7ables. Notre service client simplifie la commande de pi\u00e8ces d\u00e9tach\u00e9es, vous permettant ainsi de les obtenir rapidement et de garantir le bon fonctionnement de votre entreprise.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5545\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-5545\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Avez-vous des programmes de formation sur la fa\u00e7on d&#039;utiliser et d&#039;entretenir le granulateur et le s\u00e9parateur de fils ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5545\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-5545\"><p>Oui, bien s\u00fbr. Nous proposons des formations compl\u00e8tes et personnalis\u00e9es pour r\u00e9pondre aux besoins de votre \u00e9quipe. Ces formations abordent les aspects op\u00e9rationnels, la maintenance r\u00e9guli\u00e8re et la r\u00e9solution efficace des probl\u00e8mes. Notre objectif est de donner \u00e0 votre personnel les comp\u00e9tences n\u00e9cessaires pour utiliser efficacement les \u00e9quipements.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"How long does it usually take to get your cable granulator and separator?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Our usual delivery time is about 20~30 days, but this can change depending on things like the size, power and other details of the order. For the exact date, please get in touch with our customer service team.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Can your equipment be shipped to other countries?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Surely, we can ship all over the world, we also can help to arrange shipping and make sure packages get delivered safely on time. Delivery times and extra costs may change depending on where the package is going. Feel free to ask for more information.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What kind of help is there for the cable granulator and separator after sale?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>After the sale, we offer technical help, troubleshooting, and advice on how to do routine maintenance. We promise to keep your equipment working at its best by using responsive help systems.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Are new parts easy to find? If not, how can they be gotten?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Of course, we keep a stock of necessary extra parts that can be quickly replaced. Our customer service makes it easy to order spare parts, so you can get them quickly and keep your business running smoothly.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Do you have training programmes for how to use and take care of the wire granulator and separator?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Yes, of course. We offer full training sessions that are customized to meet the needs of your team. These sessions cover operational aspects, regular maintenance, and effective problem-solving. Our goal is to give your staff the skills they need to handle equipment efficiently.<\\\/p>\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3728dbd\" data-id=\"3728dbd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e4153d elementor-widget elementor-widget-heading\" data-id=\"3e4153d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">obtenez un devis gratuit maintenant !<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45220e7 elementor-widget elementor-widget-text-editor\" data-id=\"45220e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous aimerions collaborer avec vous. Contactez-nous pour toute question ou demande de devis. Nos experts vous r\u00e9pondront sous 24 heures et vous aideront \u00e0 choisir le granulateur et s\u00e9parateur de c\u00e2bles adapt\u00e9 \u00e0 vos besoins.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adf461b elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"adf461b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"60881\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"adf461b\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Hot Selling Cable Granulator and Separator\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"60881\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"*Nom\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"*E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"*Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>cable granulator and separator machine BSGH Granulator cable granulator and separator machines revolutionize the scrap cable recycling industry with advanced technology. Our machines specialize in efficiently separating valuable copper or aluminum from waste cables or wires. They offer high efficiency, large output, and excellent quality, catering to various recycling needs. We offer three main types [&hellip;]<\/p>","protected":false},"author":1,"featured_media":68857,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Cable Granulator and Separator - BSGH Granulator","_seopress_titles_desc":"BSGH Granulator cable granulator and separator machines redefine cable recycling through advanced technology, our machine specializes in...","_seopress_robots_index":"","_seopress_analysis_target_kw":"cable granulator and separator","footnotes":""},"class_list":["post-60881","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/pages\/60881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/comments?post=60881"}],"version-history":[{"count":0,"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/pages\/60881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/media\/68857"}],"wp:attachment":[{"href":"https:\/\/bsghgranulator.com\/fr\/wp-json\/wp\/v2\/media?parent=60881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}